{"id":4922,"date":"2022-05-20T11:27:16","date_gmt":"2022-05-20T09:27:16","guid":{"rendered":"https:\/\/www.teq-automotive.com\/about-us\/"},"modified":"2022-05-23T18:21:10","modified_gmt":"2022-05-23T16:21:10","slug":"azienda","status":"publish","type":"page","link":"https:\/\/www.teq-automotive.com\/it\/azienda\/","title":{"rendered":"Azienda"},"content":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1463994430217{margin-bottom: 30px !important;}&#8221; type=&#8221;grid&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1462381095114{padding-right: 10px !important;padding-left: 10px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1519630444469{margin-top: 0px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;}&#8221;]<\/p>\n<h2><strong>TEQ SA<\/strong><\/h2>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1653322379668{margin-top: 30px !important;}&#8221;]<strong>Automotive<\/strong><br \/>\nTEQ \u00e8 leader nei sistemi multiplex per autoveicoli basati su protocollo CAN e fornisce l\u2019elettronica di primo impianto per i maggiori costruttori di autobus in Europa.<\/p>\n<p><strong>Veicoli Elettrici<\/strong><\/p>\n<p>Il CCS &#8211; Combined Charging System &#8211; di TEQ \u00e8 una soluzione &#8220;pronta all&#8217;uso\u201d per i veicoli elettrici. Pu\u00f2 gestire una o due prese combo (lato sinistro e destro del veicoli, particolarmente utile per gli autobus urbani) e pu\u00f2 interfacciarsi con qualsiasi tipo di BMS &#8211; Battery Management System.<\/p>\n<p><strong>Gestione flotte<\/strong><br \/>\nSoluzioni satellitari per la logistica e per le aziende di trasporto pubblico. Adottato dai maggiori trasportatori italiani e dalle pi\u00f9 esigenti aziende TPL.<\/p>\n<p><strong>Infomobilit\u00e0<\/strong><br \/>\nGuida dinamica ai parcheggi disponibili nelle aree urbane, informazione all\u2019utenza sugli orari dei servizi pubblici tramite segnaletica intelligente e telefonia mobile.<\/p>\n<p><strong>Automazione<\/strong><br \/>\nSoluzioni elettroniche \u2018ad hoc\u2019 per automazione, impiantistica, macchinari ed apparecchiature.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1462381102984{padding-right: 10px !important;padding-left: 10px !important;}&#8221;][vc_single_image image=&#8221;4668&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1463994430217{margin-bottom: 30px !important;}&#8221; type=&#8221;grid&#8221;][vc_column css=&#8221;.vc_custom_1462381102984{padding-right: 10px !important;padding-left: 10px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1519906840753{margin-top: 0px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;}&#8221;]<\/p>\n<h2 style=\"text-align: center;\"><strong>Alcuni dei nostri Clienti<br \/>\n<\/strong><\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8124&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4670&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8147&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4672&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8125&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8126&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8127&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8128&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4673&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4674&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4675&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4676&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8129&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4677&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8130&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8131&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8132&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4678&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4679&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4680&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4681&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4682&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8133&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4683&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4684&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4685&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8134&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8135&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1463994430217{margin-bottom: 30px !important;}&#8221; type=&#8221;grid&#8221;][vc_column css=&#8221;.vc_custom_1462381095114{padding-right: 10px !important;padding-left: 10px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1563373642017{margin-top: 0px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;}&#8221;]<\/p>\n<h2 style=\"text-align: center;\"><strong> <\/strong><\/h2>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1563373432777{margin-top: 0px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;}&#8221;]<\/p>\n<h2 style=\"text-align: center;\"><strong>Distributore Ufficiale<br \/>\n<\/strong><\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1463994430217{margin-bottom: 30px !important;}&#8221; type=&#8221;grid&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1462381095114{padding-right: 10px !important;padding-left: 10px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1563376358861{margin-top: 30px !important;}&#8221;]TEQ \u00e8 distributore ufficiale di Mobileye\u00ae, Azienda Leader Mondiale per sistemi di anti-collisione e guida automona[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1462381102984{padding-right: 10px !important;padding-left: 10px !important;}&#8221;][vc_single_image image=&#8221;5496&#8243; img_size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:%2F%2Fwww.mobileye.com%2F|&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\"><strong>La Nostra Storia<\/strong><\/h2>\n<p>[vc_column_text]<\/p>\n<p style=\"text-align: left;\"><div class=\"tm_timeline tm_timeline-layout-vertical tm_timeline-layout-vertical-chessOrder\">\r\n\r\n\t<div class=\"tm_timeline__container\">\r\n\r\n\t\t<div class=\"tm_timeline__body\">\r\n\r\n\t\t\t<div class=\"tm_timeline__tense\"><\/div>\r\n\r\n\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">1986<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tIn quest&#039;anno inizia l&#039;attivit\u00e0 dei nostri tecnici nel settore dell&#039;elettronica.\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Le prime applicazioni furono orientate ai grandi impianti di automazione di \u2018parchi rottame\u2019 delle acciaiere. Il sistema, basandosi sulla \u2018ricetta\u2019 impostata dal sistema di alto livello, ordinava a veicoli semoventi comandati via radio di caricare le ceste vuote, di posizionarsi sotto il carro ponte e di seguirlo nei movimenti. Un display montato nella cabina del carro ponte informava il gruista sul tipo di materiale da caricare. Ogni carico veniva pesato, ed a lavoro ultimato la cesta veniva portata automaticamente all&#8217;alto forno.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">1989<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tPrime applicazioni con il CAN (Controller Area Network)\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>In collaborazione con la ditta Mauri di Desio, viene sviluppato il primo autobus urbano dotato di un sistema multiplex basato su CAN. Sar\u00e0 il primo autobus dotato di multiplex ad essere immatricolato e commercializzato.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">1991<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tLe applicazioni con il CAN sono una realt\u00e0\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Il sistema multiplex, denominato ADICOM (Automotive Digital Control Modules), trova nuovi settori di appicazione: barche, pompe per calcestruzzo con radiocomando, autogru e sollevatori di container con sistema antiribaltamento integrato, rulli compattatori di asfalto con gestione elettronica della sterzatura, semoventi per la movimentazione di navi all&#8217;interno dei cantieri e battipista.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">1992<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tRecord di velocit\u00e0\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Moregallo (Lecco). L&#8217;Ing. Fabio Buzzi, su un&#8217;imbarcazione diesel a tre punti realizza un nuovo record di velocit\u00e0: 252,277 Km\/h. Il record viene realizzato facendo la media di due passaggi consecutivi (uno ascendente ed uno discendente) tra due punti distanti 1 chilometro. I nostri ingegneri realizzano il cruscotto dell&#8217;imbarcazione che ha il delicato compito di calcolare e visualizzare i giri motore del propulsore biturbo da 10&#8217;300 cc e la velocit\u00e0, dati indispensabili al pilota per la messa a punto ed il raggiungimento di questo ambito record. Lo stesso strumento verr\u00e0 adottato da numerosi altri scafi da competizione.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">1994<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tLimitatore di velocit\u00e0 Teq-Drive\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Le direttive CEE 92\/6 e CEE 92\/24 impongono che tutti i veicoli pesanti in circolazione sul territorio europeo siano dotati di un dispositivo che ne limiti la velocit\u00e0 massima. La nostra azienda produce il TEQ-Drive, un limitatore di velocit\u00e0 molto compatto, di facile montaggio e dotato di una serie di funzioni accessorie quali l&#8217;antifurto, il regolatore di velocit\u00e0 costante ed il regolastore di giri motore. Su una serie di test effettuati da una delle maggiori case produttrici di autocarri, il TEQ-Drive risulta essere il miglior prodotto in quanto a performance: il veicolo non accusa nessuna perdita di potenza, la velocit\u00e0 massima viene limitata in modo molto regolare ed i consumi di carburante diminuiscono. Il TEQ-Drive sar\u00e0 adottato dall&#8217;esercito svizzero.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">1997<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tLeader nel settore degli autobus\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>I maggiori costruttori italiani di autobus adottano l&#8217;ADICOM, l&#8217;unico sistema che offre la diagnostica a bordo e l&#8217;intercambiabilit\u00e0 delle schede. Queste caratteristiche sono il fiore all&#8217;occhiello del nostro sistema e ci verranno copiate dalla concorrenza.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2000<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tCruscotto a norme VDV\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>\u00c8 realizzato il cruscotto che segue la direttiva VDV 234, nata da uno studio realizzato dalla Verband Deutscher Verkehrsunternehmen per gli autobus urbani a pianale ribassato, che prevede che la disposizione dei comandi del posto guida di un autobus urbano sia uguale su tutti i veicoli. IL cruscotto realizzato da TEQ si evidenzia per il design che riesce a sposare le rigide direttive della normativa e le richieste stilistiche dei costruttori.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2001<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tSistema di Gestione Flotte TeqMonitoring \u00ae\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>TEQ realizza uno straordinario strumento per la localizzazione (AVL), il monitoraggio (AVM), la logistica e la diagnostica a distanza: un computer di bordo poco pi\u00f9 grande di un pacchetto di sigarette installabile su qualsiasi veicolo ed un software di centrale semplice ed intuitivo completo di cartografia europea. Il computer di bordo racchiude un localizzatore satellitare GPS, un modem GSM\/GPRS, una radio a corto raggio, 256 MB di memoria per l\u2019archiviazione dei dati, interfacce CAN, RS232, RS485, ingressi ed uscite.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2002<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tSistema di Ausilio all&#039;Esercizio Bus Sapiens \u00ae\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Per soddisfare le esigenze delle aziende di trasporto pubblico, TEQ sviluppa Bus Sapiens<small><sup>\u00ae<\/sup><\/small>, un sistema di ausilio all&#8217;esercizio (SAE) completo, che copre tutte le necessit\u00e0 di chi deve organizzare e gestire il trasporto di passeggeri. Questo sistema SAE, permette di pianificare e gestire l&#8217;intero servizio. L&#8217;informazione all&#8217;utenza, la gestione delle comunicazioni e l&#8217;integrazione dei sottosistemi di bordo (bigliettazione, videosorveglianza, contapasseggeri), sommate alle funzionalit\u00e0 di archiviazione e statistica fanno s\u00ec che Bus Sapiens<small><sup>\u00ae<\/sup><\/small>\u00a0sia uno dei migliori sistemi presenti sul mercato.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2003<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tPi\u00f9 del 33% degli autobus urbani prodotti in Italia adotta il sistema ADICOM\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>L&#8217;affidabilit\u00e0 dei nostri prodotti e la costante ricerca della perfezione ci premia. Il nostro sistema multiplex equipaggia pi\u00f9 di un terzo degli autobus urbani finanziabili prodotti in Italia.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2003<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tPrime applicazioni nel settore della domotica (Home &amp; Building Automation)\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>La gamma di prodotti realizzata per gli automezzi, grazie alla comunicazione in rete su bus ed al telecontrollo via GSM, trova un nuovo settore di applicazione: gli stabili commerciali e le abitazioni. Viene realizzato un sistema di controllo a distanza per il monitoraggio degli accessi e del livello di gasolio nelle cisterne di numerosi edifici gestiti da un&#8217;unica amministrazione. Il sistema permette di rilevare i consumo del carburante e di inviare gli allarmi ad una centrale di controllo<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2005<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tIl sistema multiplex ADICOM integra i dati dell&#039;esercizio\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Grazie all&#8217;abbinamento tra l&#8217;ADICOM ed il sistema di gestione flotte TeqMonitoring\u00a0<small><sup>\u00ae<\/sup><\/small>, il conducente degli autobus urbani accede a tutte le informazioni relative all&#8217;esercizio direttamente sul display del cruscotto di bordo. La soluzione integrata evita l&#8217;aggiunta di dispositivi esterni quali display e tastiere, lasciando inalterato il design del cruscotto.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2005<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tCentralina di interfaccia per motori Euro 4\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>La nuova generazioni di motori Euro 4, per garantire il limite di emissioni di gas nocivi, necessita sempre pi\u00f9 dell&#8217;ausilio dell&#8217;elettronica. Tutta la gestione del motore avviene tramite &#8220;bus&#8221; e nessun segnale tradizionale \u00e8 pi\u00f9 disponibile. La centralina sviluppata da TEQ controlla il motore, il pedale dell&#8217;acceleratore e tutte le informazioni per il conducente. Vengono realizzate 2 varianti: una, in versione &#8220;strumento&#8221;, con display LCD, da installarsi nel cruscotto, ed una, pi\u00f9 semplice, che pilota gli strumenti tradizionali.<br \/>\nDeutz, fabbrica leader nella costruzione di motori, sar\u00e0 il primo costruttore ad adottare questa centralina di serie su tutti i motori destinati alla trazione.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2006<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tLa nuova sede\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Al fine di soddisfare le esigenze legate alla continua espansione, l&#8217;azienda si trasferisce nella sede di Lugano-Barbengo, situata nella zona industriale sud della citt\u00e0.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2006<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tSistema di rilevamento delle fughe di gas GPD\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>TEQ sviluppa un sensore che misura la concentrazione di gas combustibili nell&#8217;aria e calcola la percentuale di concentrazione rispetto alla LEL, cio\u00e8 il limite minimo di esplosione. Pi\u00f9 sensori, collegati ad una centralina elettronica di gestione delle bombole formano il GPD: un sistema completo per la gestione ed il monitoraggio dei circuiti di alimentazione dei veicoli a metano (gas naturale compresso &#8211; CNG). Il sistema viene adottato da Evobus, Neoman, Scania, BredaMenarini e Cacciamali-Irisbus.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2006<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tGateway per la raccolta dei dati a bordo degli autobus\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>La necessit\u00e0 di raccogliere dati manutentivi dai veicoli per sistemi remoti cresce, ed i dati forniti dalle interfacce standard non sono pi\u00f9 sufficienti. I maggiori costruttori esteri di autobus urbani (Evobus, Neoman, Scania) adottano il Gateway della TEQ, l\u2019unico in grado di fornire i dati richiesti.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2007<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tIl concetto di &#039;multiplex&#039; viene applicato nel settore farmaceutico\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>La Fedegari, leader mondiale nel settore delle macchine per la sterilizzazione, sceglie TEQ per lo sviluppo di un sistema elettronico di gestione delle autoclavi. Il sistema sfrutta il concetto di multiplex: grazie al CAN (Controller Area Network) si crea un sistema modulare di controllo ad altissima affidabilit\u00e0: ogni funzionali\u00e0 \u00e8 gestita da un modulo a microprocessore indipendente, ed un sistema di supervisione controlla il corretto funzionamento di tutte le componenti della macchina, intervenendo in caso di anomalie al fine di garantire un ciclo di sterilizzazione sicuro.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2008<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tSistema diagnostico per le batterie dei veicoli elettrici\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>TEQ collabora con MES-DEA, l&#8217;azienda produttrice delle batterie ZEBRA (acronimo di Zero Emission Battery Research Activities), note anche come batterie nichel-cloruro di sodio, e realizza un sistema di controllo e monitoraggio remoto delle batterie.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2008<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tOBD per filtri antiparticolato FAP\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Le nuove disposizioni relative ai sistemi diagnostici di bordo (OBD) in ottemperanza alla direttiva 2005\/55\/CE prescrivono di facilitare l&#8217;individuazione immediata del deterioramento o del guasto dei dispositivi di controllo delle emissioni del motore. In ottemperanza a questa direttiva TEQ sviluppa una centralina OBD per il filtro anti-particolato (FAP) che equipaggia i motori della Deutz.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2008<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tTEQParking: Sistema di infomobilit\u00e0 per la guida dinamica ai parcheggi disponibili delle aree urbane\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Risolve uno dei problemi che oggi accomuna tutte le citt\u00e0: il traffico ed il conseguente inquinamento da esso generato. La citt\u00e0 di Lucerna (Svizzera) affida a TEQ il compito di studiare un nuovo sistema di guida per indirizzare i conducenti verso i parcheggi con posti liberi tramite informazioni su pannelli a messaggio variabile.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2010<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tSviluppo nell&#039;Est Europa ed in India\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Sempre pi\u00f9 paesi adottano norme antinquinamento per ridurre le emissioni nocive, che richiedono motori con interfacce elettroniche sofisticate. Il multiplex ADICOM di TEQ soddisfa a pieno le esigenze dei costruttori che si devono rapidamente adeguare alle nuove normative: TEQ non vende infatti un prodotto, ma una soluzione, fornendo tutto il supporto necessario allo sviluppo dei veicoli moderni: dalla progettazione della parte elettrica sino alla ricerca di partner per lo sviluppo della parte telaistica.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2011<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tSupervisione remota dei cassonetti interrati per la compattazione dei rifiuti\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Un dispositivo controlla lo stato di riempimento e di funzionamento dei cassonetti interrati per i rifiuti. Una centrale operativa pu\u00f2 monitorare la percentuale di riempimento, stabilire gli orari di apertura della &#8216;bocca esterna&#8217; e verificare il corretto funzionamento del compattatore<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2012<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tIntegrazione con il Bluetooth e scarico da remoto dei dati del cronotachigrafo DTCO\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Il nuovo Computer di Bordo del sistema di gestione delle flotte TeqMonitoring\u00a0<small><sup>\u00ae<\/sup><\/small>\u00a0integra il Bluetooth, la LAN e si interfaccia direttamente con il cronotachigrafo digitale DTCO per lo scarico a distanza dei dati richiesti dalla legge, senza bisogno dover salire a bordo di ciascun veicolo con la carta aziendale.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2013<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tPremio all&#039;imprenditore Swiss Venture Club: TEQ vince il premio del pubblico\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Lo Swiss Venture Club, nomina TEQ quale finalista per il premio alle imprese ed all\u2019imprenditore della Svizzera Italiana. Una giuria composta da esponenti della scena economica della Svizzera Italiana selezione TEQ ed altre 5 aziende tra oltre 100, quali finaliste. TEQ si classifica al 4. posto e vince il premio della giuria del pubblico.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2013<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tRTPI: Informazioni in tempo reale per smartphones\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Le informazioni relative ai passaggi degli autobus sono accessibili direttamente su smarphones. Ricerca di fermate, di orari, mappa delle linee: tutte informazioni fruibili direttamente dal telefono tramite app gratuite scaricabili dagli soters ufficiali.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2014<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tSoluzione telematica per il controllo dello spargimento sale\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>TEQ realizza un sistema per la gestione ed il controllo del servizio invernale atto a garantire la sicurezza su tutte le strade di competenza del Canton Ticino. Il sistema prevede oltre alla certificazione del servizio anche la fatturazione automatica per le imprese private a cui \u00e8 stato affidato il servizio. Tutti i mezzi sono dotati del Compuer di Bordo TEQMonitoring che acquisisce i dati relativi allo spargimento del sale ed utilizzo della lama neve.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2015<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tFleet connected : i bus si interfacciano con i semafori\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>Il sistema Bus Sapiens<sup>\u00ae<\/sup> si connette con i semafori. Gli autobus comunicano il proprio stato di servizio e puntualit\u00e0 alle centraline poste nei semafori, che decidono come intevenire sulla sequenza programmata: agli autobus in ritardo viene garantita la massima priorit\u00e0 di passaggio.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-even\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2018<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tGestione delle coincidenze con le Ferrovie Federali Svizzere\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p><span style=\"font-size: 12pt;\">TEQ interfaccia tutta la rete d<\/span>ei <span style=\"font-size: 12pt;\">mezzi di trasporto pubblico del Canton Ticino con le Ferrovie Federali Svizzere grazie a Bus Sapiens<sup>\u00ae<\/sup>. Le coincidenze treno-autobus sono garantite automaticamente e tutti i dati fruibili in tempo reale.<br \/>\n<\/span><\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"tm_timeline__event tm_timeline__event-odd\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__dot\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__date\">2024<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__title\">\r\n\t\t\t\t\t\t\tDDAW Avviso di sonnolenza ed attenzione del conducente\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"tm_timeline__event__description\">\r\n\t\t\t\t\t\t<p>TEQ realizza un sistema DDAW conforme al regolamento (EU) 2019\/2144 ed al regolamento delegato (EU) 2021\/1341. Il prodotto di TEQ \u00e8 progettato per essere fornito come soluzione stand-alone &#8220;pronta all&#8217;uso&#8221; o totalmente integrato nel multiplex di TEQ.<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1463994430217{margin-bottom: 30px !important;}&#8221; type=&#8221;grid&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1462381095114{padding-right: 10px !important;padding-left: 10px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1519630444469{margin-top: 0px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;}&#8221;] TEQ SA [\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1653322379668{margin-top: 30px !important;}&#8221;]Automotive TEQ \u00e8 leader nei sistemi multiplex per autoveicoli basati su protocollo CAN e fornisce l\u2019elettronica di primo impianto per i maggiori costruttori di autobus in Europa. Veicoli Elettrici Il [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/pages\/4922"}],"collection":[{"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/comments?post=4922"}],"version-history":[{"count":19,"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/pages\/4922\/revisions"}],"predecessor-version":[{"id":8227,"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/pages\/4922\/revisions\/8227"}],"wp:attachment":[{"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/media?parent=4922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}