{"id":5433,"date":"2019-07-01T13:58:13","date_gmt":"2019-07-01T11:58:13","guid":{"rendered":"https:\/\/www.teq-automotive.com\/automation\/"},"modified":"2020-06-08T14:01:10","modified_gmt":"2020-06-08T12:01:10","slug":"automazione","status":"publish","type":"page","link":"https:\/\/www.teq-automotive.com\/it\/automazione\/","title":{"rendered":"Automazione"},"content":{"rendered":"<p>[vc_row][vc_column]\t\t<div class=\"wd-heading text-left  \" >\r\n\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t<h3 style=\"margin:0;font-family:;font-weight:400;\" >\r\n\t\t\t\t\tAutomazione\t\t\t\t<\/h3>\r\n\r\n\t\t\t\t\r\n\t\t\t\t<h4 style=\"font-family:;font-weight:400;\" >\r\n\t\t\t\t\t\t\t\t\t<\/h4>\r\n\r\n\t\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t[vc_column_text]TEQ realizza soluzioni personalizzate per le aziende che necessitano di soluzioni avanzate che sono realizzabili con prodotti commerciali standard. Le nostre soluzioni modulari offrono funzioni di diagnostica avanzate ed alta affidabilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Un esempio di un\u2019applicazione gli sterilizzatori utilizzati nel settore farmaceutico:<\/p>\n<p>TEQ ha sviluppato un sistema composto da un modulo principale ed una serie di moduli periferici a ciascuno dei quali e dedicata una funzione specifica: il modulo principale si occupa svolgere i programmi di gestione, i cicli, le fasi, di gestire le configurazioni e gli allarmi. Singoli moduli specifici gestiscono le porte, il generatore di vapore, le valvole pneumatiche, le uscite analogiche e quelle a 230V.[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;4705&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1561982078162{margin-right: 10px !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;4706&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1561982153960{margin-right: 10px !important;margin-left: 10px !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;4707&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1561982276076{margin-left: 10px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]TEQ realizza soluzioni personalizzate per le aziende che necessitano di soluzioni avanzate che sono realizzabili con prodotti commerciali standard. Le nostre soluzioni modulari offrono funzioni di diagnostica avanzate ed alta affidabilit\u00e0. &nbsp; Un esempio di un\u2019applicazione gli sterilizzatori utilizzati nel settore farmaceutico: TEQ ha sviluppato un sistema composto da un modulo principale ed una serie [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/pages\/5433"}],"collection":[{"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/comments?post=5433"}],"version-history":[{"count":4,"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/pages\/5433\/revisions"}],"predecessor-version":[{"id":7310,"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/pages\/5433\/revisions\/7310"}],"wp:attachment":[{"href":"https:\/\/www.teq-automotive.com\/it\/wp-json\/wp\/v2\/media?parent=5433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}